{"id":85155,"date":"2023-11-02T16:24:02","date_gmt":"2023-11-02T16:24:02","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=85155"},"modified":"2023-11-28T03:06:41","modified_gmt":"2023-11-28T03:06:41","slug":"villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/","title":{"rendered":"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Despu\u00e9s de 24 a\u00f1os de peronismo y algunas variantes, el radical, encabezando el espacio Juntos Por el Cambio, Ignacio Tagni, result\u00f3 elegido por amplia mayor\u00eda el pasado 25 de junio como nuevo intendente de Villa Nueva.<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Se expres\u00f3 en El Regional Diario Digital, con entusiasmo y expectativas de cara a diciembre, cuando junto a su equipo de trabajo, asumir\u00e1n como nuevas autoridades. \u201cEstoy muy preparado para llevar adelante los destinos de los villanovenses que confiaron en m\u00ed\u201d.<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Escribe: Carolina Durand<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El pasado 18 de octubre, en el auditorio de la Sala Astoria, recibieron diplomas por parte de la Junta Electoral, todas las autoridades que asumir\u00e1n cargos en la Intendencia, el Concejo Deliberante y el Tribunal de Cuentas Municipal, el pr\u00f3ximo 1\u00b0 de diciembre.<\/p>\n\n\n\n<p>El candidato electo Ignacio Tagni subray\u00f3 que la transici\u00f3n con la gesti\u00f3n actual, no estar\u00eda siendo la que pretend\u00eda que fuera y reconoci\u00f3 que, en el aniversario de la ciudad, el intendente actual, Natalio Graglia, manifest\u00f3 su predisposici\u00f3n para acompa\u00f1ar la nueva gesti\u00f3n. La cual, en la pr\u00e1ctica, seg\u00fan sus palabras no estar\u00eda llev\u00e1ndose a cabo al 100%.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"774\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Tagni-proclamacion-intendente-2023-2.jpg?resize=1024%2C774&#038;ssl=1\" alt=\"\" class=\"wp-image-84390\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Tagni-proclamacion-intendente-2023-2.jpg?resize=1024%2C774&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Tagni-proclamacion-intendente-2023-2.jpg?resize=300%2C227&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Tagni-proclamacion-intendente-2023-2.jpg?resize=768%2C580&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Tagni-proclamacion-intendente-2023-2.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption><em>El momento de la proclamaci\u00f3n como intendente electo de la ciudad. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>En palabras del radical electo, el equipo est\u00e1 incursionado en la municipalidad y poni\u00e9ndose al corriente, pero, en algunas \u00e1reas, a\u00fan no han podido acceder para tener un diagn\u00f3stico acabado. No obstante, el futuro nuevo gabinete ha tenido varias reuniones y est\u00e1 trabajando en los proyectos presentados en la plataforma de campa\u00f1a.<\/p>\n\n\n\n<p><strong>\u201cVamos a gobernar para mejorar la calidad de vida de toda la ciudadan\u00eda\u201d<\/strong><\/p>\n\n\n\n<p>\u201cLa sociedad demanda predisposici\u00f3n del Estado y de los empleados para que la ciudad crezca y se desarrolle. Demandan servicios en materia de salud, seguridad, alumbrado p\u00fablico, recolecci\u00f3n de residuos, etc. Es por eso que, nos anticipamos sobre las acciones inmediatas que tomaremos, una vez que asumamos, gracias al recorrido y diagn\u00f3stico que hemos hecho, recorriendo los barrios\u201d, remarc\u00f3 Tagni.<\/p>\n\n\n\n<p>\u201cEl 56% de la poblaci\u00f3n nos vot\u00f3 y con eso, su confianza; estamos obligados a responder a quienes nos acompa\u00f1aron y a quienes no, tambi\u00e9n, porque vamos a gobernar para mejorar la calidad de vida de toda la ciudadan\u00eda\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Ante el problema reciente en materia de recolecci\u00f3n de basura, asever\u00f3 que, pidieron el plan de acci\u00f3n que ten\u00eda el municipio ante la falta de camiones (rotos) para la recolecci\u00f3n y coment\u00f3 que \u201cconsiguieron 10 camiones y muchos voluntarios para revertir la situaci\u00f3n ambiental que llen\u00f3 los barrios de basura\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-.jpg?resize=1024%2C683&#038;ssl=1\" alt=\"\" class=\"wp-image-76869\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Auditor\u00eda: \u201cNo vamos a dejar margen a dudas\u201d<\/strong><\/p>\n\n\n\n<p>Respecto a la inspecci\u00f3n y verificaci\u00f3n de la contabilidad del municipio, el futuro intendente asever\u00f3 que, ni bien asuma, pedir\u00e1 la auditor\u00eda del estado actual, la cual, les llevar\u00eda 6 meses obtener el balance. \u201cSon extensas, complicadas, pero, queremos dar un informe urgente de cada dependencia, para mostrar en qu\u00e9 estado recibimos los recursos disponibles, las deudas, los juicios, con el fin de mostrar trasparencia desde el primer momento que gobernemos\u201d.<\/p>\n\n\n\n<p>Y agreg\u00f3: \u201cLos actos de gobierno son p\u00fablicos y todos tienen que saber en qu\u00e9 condiciones se trabaja, qui\u00e9nes son los funcionarios, a qui\u00e9n se contrata, cu\u00e1nto se les paga, qu\u00e9 se certifica, cu\u00e1l es el cronograma y duraci\u00f3n de obras\u201d.<\/p>\n\n\n\n<p>Sobre los datos que brindar\u00e1 la auditor\u00eda, resalt\u00f3: \u201cA nosotros nos cost\u00f3 much\u00edsimos a\u00f1os de pedidos de informes (los cuales innumerables no fueron respondidos) acceder a la informaci\u00f3n. Es por eso, que el pedido ha sido expl\u00edcito a quienes ser\u00e1n concejales de nuestro bloque, de que no hagan lo mismo con los concejales de la nueva oposici\u00f3n. Pedido que se pida, deber\u00e1 ser entregado\u201d.<\/p>\n\n\n\n<p>\u201cVamos a ser un gobierno abierto y transparente. Tendremos apertura y queremos trabajar en conjunto, ser\u00e1n el \u00f3rgano de contralor que nos controle, porque la sociedad los puso all\u00ed para eso, no vamos a dejar margen a la duda. Esa va a ser nuestra impronta administrativa\u201d, acot\u00f3.<\/p>\n\n\n\n<p>Tambi\u00e9n, presentar\u00e1n declaraciones juradas p\u00fablicas para que, toda la poblaci\u00f3n acceda a saber, cu\u00e1l es el patrimonio con el que ingresan a trabajar al municipio en el per\u00edodo 2023 &#8211; 2027.<\/p>\n\n\n\n<p><strong>Primeras medidas<\/strong><\/p>\n\n\n\n<p>Mientras aguardan el balance de la auditor\u00eda, empezar\u00edan a trabajar en materia de salud, con la prestaci\u00f3n de atenci\u00f3n primaria articulada, para descentralizarla y llevarla a los barrios; pondr\u00e1n en marcha un plan de acci\u00f3n para mejorar el servicio de recolecci\u00f3n de residuos, regador, arreglo de calles y alumbrado p\u00fablico.<\/p>\n\n\n\n<p>\u201cEn desarrollo social, queremos trabajadores sociales en las calles, no en las oficinas. Su trabajo de campo, diagnosticar\u00e1 la situaci\u00f3n real de los vecinos para encarar pol\u00edticas reales, concretas y focalizadas\u201d, explicit\u00f3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/06\/Tagni-festejo-intendente-2023.jpg?resize=1024%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-78659\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/06\/Tagni-festejo-intendente-2023.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/06\/Tagni-festejo-intendente-2023.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/06\/Tagni-festejo-intendente-2023.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption><em>La celebraci\u00f3n de Tagni tras el amplio triunfo electoral. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Tagni puso \u00e9nfasis al mencionar que gestionar\u00e1n a nivel provincial, la coparticipaci\u00f3n adeudada. \u201cSomos uno de los pocos municipios que no llega a pagar los sueldos con la coparticipaci\u00f3n porque no alcanza. Lo que recibimos est\u00e1 tomando con datos del 2010 con 19 mil habitantes y fuimos la que m\u00e1s ha crecido en el pa\u00eds en el \u00edndice per c\u00e1pita, estamos arriba de los 35 mil habitantes. Muchos intendentes no hablan de esto porque, su poblaci\u00f3n ha disminuido y siguen cobrando lo mismo\u201d, argument\u00f3.<\/p>\n\n\n\n<p><strong>\u00bfHay carnavales 2024?<\/strong><\/p>\n\n\n\n<p>En cuanto a los grandes eventos de la ciudad y la fiesta popular, los carnavales gigantes, asever\u00f3: \u201cYo nunca dije que no \u00edbamos a realizarlos. Mi an\u00e1lisis es, si no tengo m\u00e9dicos en el \u00e1mbito de la salud, se debe priorizar las necesidades de la gente a la hora de gastar los recursos de las arcas municipales\u201d.<\/p>\n\n\n\n<p>\u201cNuestro prop\u00f3sito, es trabajar con el sector privado en todos los eventos de gran magnitud que, al municipio le cuesta mucho dinero y se deja de atender necesidades b\u00e1sicas para el desarrollo\u201d, destac\u00f3.<\/p>\n\n\n\n<p><strong>Algunos nombres del futuro gabinete<\/strong><\/p>\n\n\n\n<p>El hist\u00f3rico radical Sergio \u201cCacho\u201d Aguilar ser\u00e1 el secretario de Gobierno.&nbsp; \u201cEste proyecto lo iniciamos juntos, con un amplio recorrido en la pol\u00edtica villanovense, fue Convencional Constituyente, es una garant\u00eda para este nuevo gobierno\u201d.<\/p>\n\n\n\n<p>La directora del colegio Rivadavia, Ana Mari Dutto, estar\u00e1 al frente de la Secretar\u00eda de Educaci\u00f3n y Cultura. \u201cTiene muchas ideas en materia de cultura para concretar y una planificaci\u00f3n interesante con programas y proyectos en materia de educaci\u00f3n y medo ambiente\u201d.<\/p>\n\n\n\n<p>Juan Vagnola es m\u00e9dico ur\u00f3logo y tendr\u00e1 a su cargo la Secretar\u00eda de Salud. \u00a0\u201cEst\u00e1 trabajando en un esquema de trabajo imponente para brindar atenci\u00f3n primaria en el Hospital y llegar a los barrios\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"901\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/07\/Graglia-y-Tagni.jpg?resize=1024%2C901&#038;ssl=1\" alt=\"\" class=\"wp-image-79148\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/07\/Graglia-y-Tagni.jpg?resize=1024%2C901&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/07\/Graglia-y-Tagni.jpg?resize=300%2C264&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/07\/Graglia-y-Tagni.jpg?resize=768%2C675&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/07\/Graglia-y-Tagni.jpg?resize=1536%2C1351&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/07\/Graglia-y-Tagni.jpg?w=2048&amp;ssl=1 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption><em>Una reuni\u00f3n entre Tagni y Graglia, como parte de la transici\u00f3n.<\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Daniel Barotto es contador y estar\u00e1 en la Secretaria de Finanzas. \u201cTiene una vasta experiencia en lo privado y conocimientos en el sector p\u00fablico\u201d. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Juan Manuel Tovo ser\u00e1 secretario de Legal y T\u00e9cnica. \u201cEst\u00e1 muy preparado en derecho administrativo y estamos muy contentos de poder incorporarlo a trabajar en el municipio\u201d.<\/p>\n\n\n\n<p>Julio Chiarini, exarquero de River, Instituto y Gimnasia y Esgrima de Jujuy de la Primera Nacional, ser\u00e1 secretario de Deporte y Turismo. \u201cSe retir\u00f3 del f\u00fatbol para formar parte de nuestro equipo, ven\u00edamos hablando hace tiempo y decidi\u00f3 no renovar contrato para venir a trabajar en Villa Nueva en materia de deporte\u201d.&nbsp;<\/p>\n\n\n\n<p>Guillermo Elorza, ingeniero civil, trabaj\u00f3 en Vialidad Provincial. \u201cConoce much\u00edsimo de desarrollo y trabajar\u00e1 con nosotros en el c\u00f3digo de edificaci\u00f3n, al que, hay que hacerle medicaciones para no tener conflictos en la gesti\u00f3n, a la hora de apostar en materia de crecimiento y desarrollo para la ciudad\u201d. \u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tambi\u00e9n pod\u00e9s ver:<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-el-regional wp-block-embed-el-regional\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Fu6x8u4QCW\"><a href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/desde-adentro-ignacio-tagni-estoy-mucho-mas-preparado-tengo-pleno-conocimiento-para-gobernar-villa-nueva\/\">[Desde Adentro] Ignacio Tagni: \u201cEstoy mucho m\u00e1s preparado, tengo pleno conocimiento para gobernar Villa Nueva\u201d<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab[Desde Adentro] Ignacio Tagni: \u201cEstoy mucho m\u00e1s preparado, tengo pleno conocimiento para gobernar Villa Nueva\u201d\u00bb \u2014 El Regional\" src=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/desde-adentro-ignacio-tagni-estoy-mucho-mas-preparado-tengo-pleno-conocimiento-para-gobernar-villa-nueva\/embed\/#?secret=VZ3sUkgfV5#?secret=Fu6x8u4QCW\" data-secret=\"Fu6x8u4QCW\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 24 a\u00f1os de peronismo y algunas variantes, el radical, encabezando el espacio Juntos Por el Cambio, Ignacio Tagni, result\u00f3 elegido por amplia mayor\u00eda el pasado 25 de junio como nuevo intendente de Villa Nueva. Se expres\u00f3 en El Regional Diario Digital, con entusiasmo y expectativas de cara a diciembre, cuando junto a su [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":76868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[2089,3557,1408],"tags":[23115,247,13485,1731,1719,175,5715,68,1736,1252,4703,395,232],"class_list":["post-85155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-tercera","category-villa-nueva","tag-abierto","tag-auditoria","tag-carnavales","tag-gabinete","tag-gestion","tag-gobierno","tag-ignacio-tagni","tag-intendente","tag-medidas","tag-natalio-graglia","tag-propuestas","tag-transparencia","tag-villa-nueva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d - El Regional\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de 24 a\u00f1os de peronismo y algunas variantes, el radical, encabezando el espacio Juntos Por el Cambio, Ignacio Tagni, result\u00f3 elegido por amplia mayor\u00eda el pasado 25 de junio como nuevo intendente de Villa Nueva. Se expres\u00f3 en El Regional Diario Digital, con entusiasmo y expectativas de cara a diciembre, cuando junto a su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-02T16:24:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T03:06:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d\",\"datePublished\":\"2023-11-02T16:24:02+00:00\",\"dateModified\":\"2023-11-28T03:06:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/\"},\"wordCount\":1333,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1\",\"keywords\":[\"abierto\",\"Auditoria\",\"carnavales\",\"gabinete\",\"gesti\u00f3n\",\"gobierno\",\"Ignacio Tagni\",\"intendente\",\"medidas\",\"Natalio Graglia\",\"propuestas\",\"transparencia\",\"VILLA NUEVA\"],\"articleSection\":[\"Pol\u00edtica\",\"tercera\",\"Villa Nueva\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/\",\"name\":\"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2023-11-02T16:24:02+00:00\",\"dateModified\":\"2023-11-28T03:06:41+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/","og_locale":"es_ES","og_type":"article","og_title":"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d - El Regional","og_description":"Despu\u00e9s de 24 a\u00f1os de peronismo y algunas variantes, el radical, encabezando el espacio Juntos Por el Cambio, Ignacio Tagni, result\u00f3 elegido por amplia mayor\u00eda el pasado 25 de junio como nuevo intendente de Villa Nueva. Se expres\u00f3 en El Regional Diario Digital, con entusiasmo y expectativas de cara a diciembre, cuando junto a su [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-11-02T16:24:02+00:00","article_modified_time":"2023-11-28T03:06:41+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg","type":"image\/jpeg"}],"author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d","datePublished":"2023-11-02T16:24:02+00:00","dateModified":"2023-11-28T03:06:41+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/"},"wordCount":1333,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1","keywords":["abierto","Auditoria","carnavales","gabinete","gesti\u00f3n","gobierno","Ignacio Tagni","intendente","medidas","Natalio Graglia","propuestas","transparencia","VILLA NUEVA"],"articleSection":["Pol\u00edtica","tercera","Villa Nueva"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/","name":"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1","datePublished":"2023-11-02T16:24:02+00:00","dateModified":"2023-11-28T03:06:41+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/villa-nueva-ignacio-tagni-vamos-a-ser-un-gobierno-abierto-y-transparente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"[Villa Nueva] Ignacio Tagni: \u201cVamos a ser un gobierno abierto y transparente\u201d"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/05\/Ignacio-Tagni-primer-plano.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/85155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=85155"}],"version-history":[{"count":3,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/85155\/revisions"}],"predecessor-version":[{"id":85159,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/85155\/revisions\/85159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/76868"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=85155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=85155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=85155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}