{"id":85174,"date":"2023-11-02T21:12:31","date_gmt":"2023-11-02T21:12:31","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=85174"},"modified":"2023-11-06T19:55:21","modified_gmt":"2023-11-06T19:55:21","slug":"el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/","title":{"rendered":"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad?"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Escribe: Miguel Andreis<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Apenas en dos semanas y ya entraremos en una de las etapas m\u00e1s complejas y controversiales de la historia pol\u00edtica y social argentina. &nbsp;El balotaje.<\/p>\n\n\n\n<p>Referirse a datos que arrojan las encuestadoras no ser\u00eda demasiado serio y objetivo. Si es que hay algo serio en nuestro pa\u00eds. El resultado tiene m\u00e1s de dos vertientes. M\u00e1s de dos candidatos, aunque de uno de ellos saldr\u00e1 el futuro Presidente: Massa o Milei.<\/p>\n\n\n\n<p>En el medio millones de connacionales que ingresaron en el t\u00fanel de las dudas existenciales. \u00bfSufragar por qui\u00e9n y para qu\u00e9? Uno y otro hicieron de la decepci\u00f3n una manera de fomentar la incredulidad. La falacia, el cinismo y la destrucci\u00f3n de la memoria fue una constante de ambos lados.\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"982\" height=\"654\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Massa-Milei-1.jpg?resize=982%2C654&#038;ssl=1\" alt=\"\" class=\"wp-image-84565\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Massa-Milei-1.jpg?w=982&amp;ssl=1 982w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Massa-Milei-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/10\/Massa-Milei-1.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"(max-width: 982px) 100vw, 982px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>La otra opci\u00f3n es no concurrir a los comicios, algo que suena a disparatado si tomamos en cuenta lo estoico que fue recuperar el derecho al voto. A elegir.<\/p>\n\n\n\n<p>No obstante, ninguno seduce, ninguno es cre\u00edble, la sospecha de fraudes por parte del oficialismo nunca se dilucid\u00f3, aunque las exposiciones, con datos sobre la tem\u00e1tica se expusieron por miles.<\/p>\n\n\n\n<p>La Justicia no investig\u00f3 los elementos puestos en valor. Llama la atenci\u00f3n el silencio de los actores, l\u00e9ase candidatos y especialmente de la oposici\u00f3n. Actuando casi como c\u00f3mplices.&nbsp;<\/p>\n\n\n\n<p><strong>Hay que votar porque\u2026<\/strong><\/p>\n\n\n\n<p>Lo extra\u00f1o, o no deber\u00eda serlo tanto, es observar de la manera que se quiere defenestrar al voto en blanco, nulo o la no concurrencia. \u00bfAlguien puede asegurar que en esta ocasi\u00f3n estaremos frente a sufragios limpios y transparentes?<\/p>\n\n\n\n<p>No siempre un accionar honesto genera votos, pero s\u00ed, la apertura de conciencia sobre lo que deber\u00eda ser una democracia real, que no es la que nos rige, donde la corrupci\u00f3n y la impunidad vuelan con la m\u00e1s absoluta libertad.<\/p>\n\n\n\n<p>Esta degradaci\u00f3n de la palabra, de los principios, de los valores del modo de vida, no nos va a ser gratis. Y se fue \u201cconstruyendo\u201d con el mismo discurso de acci\u00f3n que nos somete desde hace tiempo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong>Esto no es una democracia, es una autocracia mal disfrazada, desquiciada y falaz, donde la farsa y la falsedad, por un lado, van de la mano de la esquizofrenia y la paranoia\u2026 Uno y otro.<\/strong><\/p><\/blockquote><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Vale interrogarse, tiene la misma autoridad un gobierno que haya cosechado menos o igual cantidad de votos que aquellos que eligieron las otras opciones, como el blanco o el no sufragar. Seguramente no. En ese caso la ciudadan\u00eda no ver\u00eda reflejada sus aspiraciones. Adem\u00e1s, vale acaso recordar, tomando aquel gobierno de una minor\u00eda, el de Arturo Umberto Ill\u00eda, uno de los mandatarios m\u00e1s honestos y probos que se sentaran en el Sill\u00f3n de Rivadavia, a qui\u00e9n la dictadura de los sesenta en consonancia con un sindicalismo bur\u00f3crata y corrupto, \u201ccolumna vertebral del movimiento peronista\u201d como se defin\u00edan, rompieron el sistema constitucional, dejando al pa\u00eds vac\u00edo de poder.<\/p>\n\n\n\n<p>Es verdad que esta fuerza gan\u00f3 con un 23% de los votos. El Justicialismo estaba proscripto por la Dictadura, hoy, no se trata de proscripci\u00f3n, sino de una convicci\u00f3n que se multiplica entre la ciudadan\u00eda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/08\/elecciones-nacionales-urna-voto.jpg?resize=911%2C567&#038;ssl=1\" alt=\"\" class=\"wp-image-80431\" width=\"911\" height=\"567\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/08\/elecciones-nacionales-urna-voto.jpg?w=820&amp;ssl=1 820w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/08\/elecciones-nacionales-urna-voto.jpg?resize=300%2C187&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/08\/elecciones-nacionales-urna-voto.jpg?resize=768%2C478&amp;ssl=1 768w\" sizes=\"(max-width: 911px) 100vw, 911px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Prima la decepci\u00f3n. \u00a0Ni Milei ni Massa despiertan expectativas serias y cre\u00edbles. Y si no son admisibles, aceptables, por qu\u00e9 querer imponer en las urnas a candidatos que sabemos -o en todo caso presumimos- por lo visto en sus diferentes acciones hasta el momento, que son absolutamente inveros\u00edmiles e inaceptables. Los dos. \u00a0<\/p>\n\n\n\n<p>Esto no es una democracia, es una autocracia mal disfrazada, desquiciada y falaz, donde la farsa y la falsedad, por un lado, van de la mano de la esquizofrenia y la paranoia\u2026 Uno y otro.<\/p>\n\n\n\n<p>O estos candidatos, ahora que lo han intentado purificar, no son los mismos que elaboraron bajo los peores desprop\u00f3sitos, torpezas y disparates el manual de la desesperanza sobre el pa\u00eds al que nos quieren llevar.<\/p>\n\n\n\n<p>Es verdad que el voto en blanco, el anulado, el no concurrir no es la esencia de un sistema democr\u00e1tico\u2026 Pero vale preguntarse: \u00bfAcaso no es peor avalar algo que de democr\u00e1tico no tiene absolutamente nada, solo una parodia, acreditando con un sufragio casi obligado elegir para saber qui\u00e9n nos condenar\u00e1 a un camino de enormes turbulencias e incierto transitar?<\/p>\n\n\n\n<p>No se trata de predecir o pronosticar, es solo no olvidar la historia m\u00e1s reciente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tambi\u00e9n pod\u00e9s ver:<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-el-regional wp-block-embed-el-regional\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"rZ1fBzsV11\"><a href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-la-parodia-del-voto-en-blanco-o-a-quien-premiar\/\">[El Deschave] La parodia del voto en blanco o a qui\u00e9n \u201cpremiar\u201d \u2026<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab[El Deschave] La parodia del voto en blanco o a qui\u00e9n \u201cpremiar\u201d \u2026\u00bb \u2014 El Regional\" src=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-la-parodia-del-voto-en-blanco-o-a-quien-premiar\/embed\/#?secret=pG2paumvj4#?secret=rZ1fBzsV11\" data-secret=\"rZ1fBzsV11\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Miguel Andreis Apenas en dos semanas y ya entraremos en una de las etapas m\u00e1s complejas y controversiales de la historia pol\u00edtica y social argentina. &nbsp;El balotaje. Referirse a datos que arrojan las encuestadoras no ser\u00eda demasiado serio y objetivo. Si es que hay algo serio en nuestro pa\u00eds. El resultado tiene m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":85176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[365,3557],"tags":[18566,3819,1535,57,631,268,673,15352,23108],"class_list":["post-85174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","category-tercera","tag-balotaje","tag-burla","tag-democracia","tag-derechos","tag-el-deschave","tag-elecciones","tag-massa","tag-milei","tag-voto-en-blanco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad? - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad? - El Regional\" \/>\n<meta property=\"og:description\" content=\"Escribe: Miguel Andreis Apenas en dos semanas y ya entraremos en una de las etapas m\u00e1s complejas y controversiales de la historia pol\u00edtica y social argentina. &nbsp;El balotaje. Referirse a datos que arrojan las encuestadoras no ser\u00eda demasiado serio y objetivo. Si es que hay algo serio en nuestro pa\u00eds. El resultado tiene m\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-02T21:12:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T19:55:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1196\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad?\",\"datePublished\":\"2023-11-02T21:12:31+00:00\",\"dateModified\":\"2023-11-06T19:55:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/\"},\"wordCount\":783,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1\",\"keywords\":[\"balotaje\",\"Burla\",\"Democracia\",\"derechos\",\"El Deschave\",\"elecciones\",\"Massa\",\"Milei\",\"voto en blanco\"],\"articleSection\":[\"Opini\u00f3n\",\"tercera\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/\",\"name\":\"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad? - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1\",\"datePublished\":\"2023-11-02T21:12:31+00:00\",\"dateModified\":\"2023-11-06T19:55:21+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1\",\"width\":1196,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad?\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad? - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/","og_locale":"es_ES","og_type":"article","og_title":"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad? - El Regional","og_description":"Escribe: Miguel Andreis Apenas en dos semanas y ya entraremos en una de las etapas m\u00e1s complejas y controversiales de la historia pol\u00edtica y social argentina. &nbsp;El balotaje. Referirse a datos que arrojan las encuestadoras no ser\u00eda demasiado serio y objetivo. Si es que hay algo serio en nuestro pa\u00eds. El resultado tiene m\u00e1s de [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-11-02T21:12:31+00:00","article_modified_time":"2023-11-06T19:55:21+00:00","og_image":[{"width":1196,"height":669,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg","type":"image\/jpeg"}],"author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad?","datePublished":"2023-11-02T21:12:31+00:00","dateModified":"2023-11-06T19:55:21+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/"},"wordCount":783,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1","keywords":["balotaje","Burla","Democracia","derechos","El Deschave","elecciones","Massa","Milei","voto en blanco"],"articleSection":["Opini\u00f3n","tercera"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/","name":"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad? - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1","datePublished":"2023-11-02T21:12:31+00:00","dateModified":"2023-11-06T19:55:21+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1","width":1196,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-que-es-peor-votar-sin-convencimiento-o-no-avalar-a-quienes-se-burlan-de-la-sociedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"[El Deschave] Qu\u00e9 es peor: \u00bfVotar sin convencimiento o no avalar a quienes se burlan de la sociedad?"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/11\/Massa-Milei-enfrentados.jpg?fit=1196%2C669&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/85174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=85174"}],"version-history":[{"count":2,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/85174\/revisions"}],"predecessor-version":[{"id":85178,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/85174\/revisions\/85178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/85176"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=85174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=85174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=85174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}