{"id":87591,"date":"2023-12-21T04:12:15","date_gmt":"2023-12-21T04:12:15","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=87591"},"modified":"2023-12-27T03:29:43","modified_gmt":"2023-12-27T03:29:43","slug":"el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/","title":{"rendered":"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente?"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Escribe: Miguel Andreis<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Una lucha de contrincantes desiguales<\/strong><\/p>\n\n\n\n<p>Una se\u00f1ora entrada en edad, notoriamente molesta, esta ma\u00f1ana en una farmacia, devolv\u00eda un pomo de pasta dental porque le quer\u00edan cobrar 9 mil pesos. Pens\u00e9 que se trataba de alguna marca especial con fines terap\u00e9uticos. Luego recorr\u00ed la estanter\u00eda y, si bien hab\u00eda m\u00e1s econ\u00f3micas, las cifras sonaban a impensadas.<\/p>\n\n\n\n<p>En mi cabeza daba vueltas sobre lo que ocurrir\u00eda con la marcha de movimientos sociales y de la izquierda en Buenos Aires por la tarde. Es tanta la dependencia que tenemos con el porte\u00f1ismo que hasta estamos, siempre preocupados, queriendo saber qu\u00e9 calles cortan o por d\u00f3nde se puede circular.<\/p>\n\n\n\n<p>Por una parte, el gobierno desgran\u00f3 toda su artiller\u00eda comunicacional como para amedrentar a aquellos que se quisieran sumar a la movilizaci\u00f3n. Las alertas fueron exponenciales, especialmente para aquellos que cobran los planes o asignaciones. Temieron.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"987\" height=\"555\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/marcha-piquetera-protocolo-20-diciembre-2023.jpg?resize=987%2C555&#038;ssl=1\" alt=\"\" class=\"wp-image-87595\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/marcha-piquetera-protocolo-20-diciembre-2023.jpg?w=987&amp;ssl=1 987w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/marcha-piquetera-protocolo-20-diciembre-2023.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/marcha-piquetera-protocolo-20-diciembre-2023.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 987px) 100vw, 987px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Tambi\u00e9n r\u00e1pidamente se conoci\u00f3 que todo el peso del reclutamiento de marginados recaer\u00eda en el dirigente de Polo Obrero Eduardo Belliboni y un grupo acotado de la Izquierda. Ser\u00eda un d\u00eda crucial para el pa\u00eds y, especialmente para el futuro del presidente Javier Milei. Tambi\u00e9n para Patricia Bullrich.<\/p>\n\n\n\n<p>Ni la CGT, ni la CTA, ni el Grupo Evita y varios etc\u00e9teras m\u00e1s prefirieron no subir al ring. Era m\u00e1s c\u00f3modo observarlo por la pantalla. Al fin y al cabo, lo hicieron Milei y Bullrich desde la sede de la Polic\u00eda Federal.<\/p>\n\n\n\n<p>Aproximadamente marcharon unas 6 mil personas.&nbsp; Quiz\u00e1s un poco m\u00e1s, no cambia demasiado. Las fuerzas de seguridad totalmente relajadas recorr\u00edan la cuadr\u00edcula con suma tranquilidad. Nada las pon\u00eda en peligro. Por su parte, Axel Kicilloff dijo que las fuerzas armadas suyas no saldr\u00edan a reprimir.&nbsp;<\/p>\n\n\n\n<p>Mucha gente, aunque muy alejada de aquel territorio festejaron lo que se tom\u00f3 como un triunfo del actual gobierno. Creyeron y tal vez as\u00ed sea, que se acababan los patrones de las calles. Como si se tratase del fin de una metodolog\u00eda que CFK, vaya el tiempo, cuestion\u00f3 en un discurso por el a\u00f1o 2014 y luego se olvid\u00f3, o hasta acompa\u00f1\u00f3 a los movilizados.<\/p>\n\n\n\n<p>Aquel alegato compartido por millones, hoy d\u00eda se viraliz\u00f3. Ser\u00eda lo que podemos definir (como me murmura mi amigo Paco), parte del realismo m\u00e1gico al palo\u2026 en definitiva nadie resiste un archivo. O no, do\u00f1a Cristina.<\/p>\n\n\n\n<p><strong>La visi\u00f3n de unos y otros<\/strong><\/p>\n\n\n\n<p>Lo importante pas\u00f3 a ser el discurso del presidente y toda una larga lista de DNU (Decretos de Necesidad y Urgencia) que pasar\u00edan por la noche. No dejaba charcos sin pisar y, salpicar a propios y extra\u00f1os. Millones de argentinos esperamos no sin ansiedad lo que anunciar\u00eda. Tal vez el futuro de Argentina y sus costos, pase por sus proclamas.<\/p>\n\n\n\n<p>En primera instancia, muchas de las notificaciones cayeron bien o muy bien a algunos y, como hay pocas grietas, totalmente opuesto a tantos otros. Posiblemente sean necesarios, casi imprescindibles, pero las consecuencias que se observan en la vidriera no parecen menores.<\/p>\n\n\n\n<p>A punto tal y vaya con las sorpresas, ollas, cucharones, tarros que hac\u00edan cuatro a\u00f1os que estaban guardados, fueron usados nuevamente en barrios como Palermo y otros de caracter\u00edsticas socioecon\u00f3micas similares.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/masivo-cacerolazo-contra-el-anuncio-milei.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87594\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/masivo-cacerolazo-contra-el-anuncio-milei.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/masivo-cacerolazo-contra-el-anuncio-milei.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/masivo-cacerolazo-contra-el-anuncio-milei.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/masivo-cacerolazo-contra-el-anuncio-milei.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00bfLos hac\u00edan sonar como un son de acompa\u00f1amientos a los anuncios o de repudio? Hasta el momento de escribir estas l\u00edneas no lo pude descifrar ya que dos personas entrevistadas por la televisi\u00f3n hablaban de razones contrapuestas. Es lo que somos como pa\u00eds.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sigue la casta pol\u00edtica durmiendo la siesta\u2026 la empresarial agradecida<\/strong><\/h4>\n\n\n\n<p><\/p>\n\n\n\n<p>A simple razonamiento algunas proclamas parecer\u00edan acertadas y otras disparatadas. Lo real, es que a las pocas horas se fueron formalizando las reuniones en sectores gremiales, sindicales y representaciones empresariales, cada qui\u00e9n con su norte.<\/p>\n\n\n\n<p>&nbsp;Eran llamados urgentes. El presidente no hab\u00eda hecho otra cosa que llevar adelante contextos de los prometidos. Y olvidos tambi\u00e9n.<\/p>\n\n\n\n<p>Claro, que cuando sus seguidores te enrostran que ellos pusieron un 56% en las urnas, se olvidan que el ballotage fue una \u201copci\u00f3n\u201d no una elecci\u00f3n. No se puede obviar que se trata de un gobierno legal y leg\u00edtimo desde lo democr\u00e1tico, pero lo legal y leg\u00edtimo no es imperecedero ni absoluto.<\/p>\n\n\n\n<p>En el medio, millones de connacionales nos quedamos esperando, al menos, un cross a la \u201ccasta\u201d. Nada de nada.&nbsp; O un directo a aquellos sectores que en estos tiempos y bajo la mayor impunidad, est\u00e1n acumulando divisas de manera portentosa y obscena: los bancos, el sistema financiero, las petroleras \u2013en un soplido aumentaron el 80% los combustibles-; las compa\u00f1\u00edas energ\u00e9ticas; la industria farmac\u00e9utica, los hacedores de los productos alimenticios, solo por citar algunas: Bunge, Dreyfus; Molinos, don Roberto Urqu\u00eda; ya no sabr\u00e1n en qu\u00e9 parte del mundo amontonar los verdes que se llevan del pa\u00eds.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-cadena-nacional-decretazo.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87575\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-cadena-nacional-decretazo.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-cadena-nacional-decretazo.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-cadena-nacional-decretazo.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-cadena-nacional-decretazo.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>La casta, s\u00ed la casta ah\u00ed sigue jugando a la escondidas con el poder<\/strong><\/h4>\n\n\n\n<p><\/p>\n\n\n\n<p>La casta, s\u00ed la casta ah\u00ed sigue jugando a la escondidas con el poder. Vale preguntarse: \u00bfEn qu\u00e9 curva perdieron las denuncias que iban a hacer? Con los responsables que detonan el pa\u00eds desde hace d\u00e9cadas. &nbsp;<\/p>\n\n\n\n<p>Argentina no est\u00e1 como est\u00e1 porque hayamos perdido una guerra, o un cataclismo. Existimos as\u00ed porque uno y otro gobernante por a\u00f1os fueron ineptos y en su mayor\u00eda delincuentes. Corruptos. \u00bfNadie piensa en llevarlos a la Justicia? O los necesitan para que voten lo que no puede pasar la barrera de los DNU.<\/p>\n\n\n\n<p>Ser\u00eda estupendo, prodigioso que al presidente y al pa\u00eds le vaya bien. Que se logre un estado equilibrado. Hasta el momento es la clase trabajadora y la clase media la que recibe los golpes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Si es por los bolsillos, dir\u00eda que estamos cerca, pero muy cerca del nocaut<\/strong><\/h4>\n\n\n\n<p><\/p>\n\n\n\n<p>Si es por los bolsillos dir\u00eda que estamos cerca, pero muy cerca del nocaut. Nadie le dijo al poder actuante algo m\u00ednimo, elemental, casi visceral, todos estos cambios pueden ser buenos o no, pero no se olviden de ponerle algo de dinero en los bolsillos de la gente, del laburante, del jubilado\u2026<\/p>\n\n\n\n<p>Eso, se\u00f1or presidente, es una omisi\u00f3n, burla o negligencia que siempre sale caro. Usted decida el camino que quiera tomar\u2026 El aturdimiento lleva a olvidar lo leg\u00edtimo y legal.<\/p>\n\n\n\n<p>Piense en algo muy simple, lo dif\u00edcil que es vivir sin pasta dental&#8230;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tambi\u00e9n pod\u00e9s ver: <\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-el-regional wp-block-embed-el-regional\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ylemRiPDS7\"><a href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/decretazo-de-milei-polemica-y-cacerolazos-cuales-son-las-30-propuestas-de-reformas-de-un-total-de-300\/\">Decretazo de Milei, pol\u00e9mica y cacerolazos: Cu\u00e1les son las 30 propuestas de reformas de un total de 300<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abDecretazo de Milei, pol\u00e9mica y cacerolazos: Cu\u00e1les son las 30 propuestas de reformas de un total de 300\u00bb \u2014 El Regional\" src=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/decretazo-de-milei-polemica-y-cacerolazos-cuales-son-las-30-propuestas-de-reformas-de-un-total-de-300\/embed\/#?secret=m0jW3v9OIs#?secret=ylemRiPDS7\" data-secret=\"ylemRiPDS7\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Miguel Andreis Una lucha de contrincantes desiguales Una se\u00f1ora entrada en edad, notoriamente molesta, esta ma\u00f1ana en una farmacia, devolv\u00eda un pomo de pasta dental porque le quer\u00edan cobrar 9 mil pesos. Pens\u00e9 que se trataba de alguna marca especial con fines terap\u00e9uticos. Luego recorr\u00ed la estanter\u00eda y, si bien hab\u00eda m\u00e1s econ\u00f3micas, las [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":87593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[365,3557],"tags":[23289,23290,16157,3574,3575,631,2058,1504,15352,44,15110,61],"class_list":["post-87591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","category-tercera","tag-20-de-diciembre","tag-cacerolazos","tag-casta","tag-decreto","tag-dnu","tag-el-deschave","tag-ingresos","tag-jubilados","tag-milei","tag-poder","tag-reformas","tag-trabajadores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente? - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente? - El Regional\" \/>\n<meta property=\"og:description\" content=\"Escribe: Miguel Andreis Una lucha de contrincantes desiguales Una se\u00f1ora entrada en edad, notoriamente molesta, esta ma\u00f1ana en una farmacia, devolv\u00eda un pomo de pasta dental porque le quer\u00edan cobrar 9 mil pesos. Pens\u00e9 que se trataba de alguna marca especial con fines terap\u00e9uticos. Luego recorr\u00ed la estanter\u00eda y, si bien hab\u00eda m\u00e1s econ\u00f3micas, las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T04:12:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-27T03:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Andreis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Andreis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/\"},\"author\":{\"name\":\"Miguel Andreis\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/df5ff3f005acf29788aed9cb359f1193\"},\"headline\":\"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente?\",\"datePublished\":\"2023-12-21T04:12:15+00:00\",\"dateModified\":\"2023-12-27T03:29:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/\"},\"wordCount\":1134,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1\",\"keywords\":[\"20 de diciembre\",\"cacerolazos\",\"casta\",\"decreto\",\"DNU\",\"El Deschave\",\"Ingresos\",\"Jubilados\",\"Milei\",\"poder\",\"reformas\",\"trabajadores\"],\"articleSection\":[\"Opini\u00f3n\",\"tercera\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/\",\"name\":\"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente? - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2023-12-21T04:12:15+00:00\",\"dateModified\":\"2023-12-27T03:29:43+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/df5ff3f005acf29788aed9cb359f1193\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente?\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/df5ff3f005acf29788aed9cb359f1193\",\"name\":\"Miguel Andreis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c643381cd03da38327c6407e6886e7182d881f2ecf94a7902ca262c41f9d8884?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c643381cd03da38327c6407e6886e7182d881f2ecf94a7902ca262c41f9d8884?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c643381cd03da38327c6407e6886e7182d881f2ecf94a7902ca262c41f9d8884?s=96&d=mm&r=g\",\"caption\":\"Miguel Andreis\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/miguelandreis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente? - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/","og_locale":"es_ES","og_type":"article","og_title":"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente? - El Regional","og_description":"Escribe: Miguel Andreis Una lucha de contrincantes desiguales Una se\u00f1ora entrada en edad, notoriamente molesta, esta ma\u00f1ana en una farmacia, devolv\u00eda un pomo de pasta dental porque le quer\u00edan cobrar 9 mil pesos. Pens\u00e9 que se trataba de alguna marca especial con fines terap\u00e9uticos. Luego recorr\u00ed la estanter\u00eda y, si bien hab\u00eda m\u00e1s econ\u00f3micas, las [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-12-21T04:12:15+00:00","article_modified_time":"2023-12-27T03:29:43+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg","type":"image\/jpeg"}],"author":"Miguel Andreis","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Miguel Andreis","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/"},"author":{"name":"Miguel Andreis","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/df5ff3f005acf29788aed9cb359f1193"},"headline":"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente?","datePublished":"2023-12-21T04:12:15+00:00","dateModified":"2023-12-27T03:29:43+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/"},"wordCount":1134,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1","keywords":["20 de diciembre","cacerolazos","casta","decreto","DNU","El Deschave","Ingresos","Jubilados","Milei","poder","reformas","trabajadores"],"articleSection":["Opini\u00f3n","tercera"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/","name":"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente? - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1","datePublished":"2023-12-21T04:12:15+00:00","dateModified":"2023-12-27T03:29:43+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/df5ff3f005acf29788aed9cb359f1193"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/el-deschave-20-de-diciembre-extrano-dia-marchas-anuncios-y-promesas-incumplidas-no-se-olvido-de-algo-senor-presidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"[El Deschave] 20 de diciembre, extra\u00f1o d\u00eda: Marchas, anuncios y promesas incumplidas\u2026 \u00bfNo se olvid\u00f3 de algo se\u00f1or presidente?"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/df5ff3f005acf29788aed9cb359f1193","name":"Miguel Andreis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c643381cd03da38327c6407e6886e7182d881f2ecf94a7902ca262c41f9d8884?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c643381cd03da38327c6407e6886e7182d881f2ecf94a7902ca262c41f9d8884?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c643381cd03da38327c6407e6886e7182d881f2ecf94a7902ca262c41f9d8884?s=96&d=mm&r=g","caption":"Miguel Andreis"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/miguelandreis\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/Milei-en-las-sombras-asuncion.jpg?fit=1280%2C720&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=87591"}],"version-history":[{"count":3,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87591\/revisions"}],"predecessor-version":[{"id":87598,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87591\/revisions\/87598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/87593"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=87591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=87591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=87591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}