{"id":87614,"date":"2023-12-21T22:43:12","date_gmt":"2023-12-21T22:43:12","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=87614"},"modified":"2023-12-22T02:26:46","modified_gmt":"2023-12-22T02:26:46","slug":"la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/","title":{"rendered":"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla"},"content":{"rendered":"\n<p>Con motivo de recordar y resignificar la fiesta de la Navidad, se llevaron a cabo celebraciones alusivas y tradicionales en la explanada de la Iglesia Catedral, las cuales se replicar\u00e1n ma\u00f1ana en la Capilla Nuestra Se\u00f1ora del Valle.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.49.jpeg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87618\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.49.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.49.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.49.jpeg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.49.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Este mi\u00e9rcoles por la noche, el intendente local, Eduardo Accastello, junto a autoridades municipales, visitaron la explanada de la Iglesia Catedral para disfrutar del pesebre viviente y la misa criolla, signos de religiosidad popular que invitan a recordar y resignificar la fiesta de la Navidad, adem\u00e1s de compartir un momento en familia y comunidad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.45.jpeg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87615\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.45.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.45.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.45.jpeg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.45.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>En este sentido, grandes, ni\u00f1os y familias completas de nuestra ciudad tambi\u00e9n acudieron a la cita, de la que participaron los padres Pedro Luchesse y Alberto Bustamante. Las representaciones art\u00edsticas estuvieron a cargo del elenco de teatro Serendipia, el grupo folcl\u00f3rico Kallpa y los artistas Andr\u00e9s Parodi y Gabriel Rios.<\/p>\n\n\n\n<p>Es as\u00ed que, la Municipalidad invita a las y los villamarienses a la segunda edici\u00f3n del pesebre viviente y misa criolla, que tendr\u00e1 lugar ma\u00f1ana, viernes 22, a partir de las 21:00 horas en la Capilla Nuestra Se\u00f1ora del Valle (calle Sucre 350) del barrio Roque S\u00e1enz Pe\u00f1a.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.54.jpeg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87617\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.54.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.54.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.54.jpeg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.54.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Acompa\u00f1aron al jefe comunal el presidente del Concejo Deliberante, Juan Pablo Inglese; el secretario de Gobierno, Cultura y Relaciones Institucionales, Marcos Bovo y su hom\u00f3logo de Unidad Intendencia, Agust\u00edn Turletti Mino. Tambi\u00e9n estuvo presente el concejal Carlos Ronco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de recordar y resignificar la fiesta de la Navidad, se llevaron a cabo celebraciones alusivas y tradicionales en la explanada de la Iglesia Catedral, las cuales se replicar\u00e1n ma\u00f1ana en la Capilla Nuestra Se\u00f1ora del Valle. Este mi\u00e9rcoles por la noche, el intendente local, Eduardo Accastello, junto a autoridades municipales, visitaron la explanada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-87614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","category-villa-maria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla - El Regional\" \/>\n<meta property=\"og:description\" content=\"Con motivo de recordar y resignificar la fiesta de la Navidad, se llevaron a cabo celebraciones alusivas y tradicionales en la explanada de la Iglesia Catedral, las cuales se replicar\u00e1n ma\u00f1ana en la Capilla Nuestra Se\u00f1ora del Valle. Este mi\u00e9rcoles por la noche, el intendente local, Eduardo Accastello, junto a autoridades municipales, visitaron la explanada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T22:43:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-22T02:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla\",\"datePublished\":\"2023-12-21T22:43:12+00:00\",\"dateModified\":\"2023-12-22T02:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/\"},\"wordCount\":259,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1\",\"articleSection\":[\"Sociedad\",\"Villa Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/\",\"name\":\"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2023-12-21T22:43:12+00:00\",\"dateModified\":\"2023-12-22T02:26:46+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/","og_locale":"es_ES","og_type":"article","og_title":"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla - El Regional","og_description":"Con motivo de recordar y resignificar la fiesta de la Navidad, se llevaron a cabo celebraciones alusivas y tradicionales en la explanada de la Iglesia Catedral, las cuales se replicar\u00e1n ma\u00f1ana en la Capilla Nuestra Se\u00f1ora del Valle. Este mi\u00e9rcoles por la noche, el intendente local, Eduardo Accastello, junto a autoridades municipales, visitaron la explanada [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-12-21T22:43:12+00:00","article_modified_time":"2023-12-22T02:26:46+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg","type":"image\/jpeg"}],"author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla","datePublished":"2023-12-21T22:43:12+00:00","dateModified":"2023-12-22T02:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/"},"wordCount":259,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1","articleSection":["Sociedad","Villa Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/","name":"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1","datePublished":"2023-12-21T22:43:12+00:00","dateModified":"2023-12-22T02:26:46+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-noche-del-miercoles-tuvo-celebracion-del-pesebre-viviente-y-la-misa-criolla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"La noche del mi\u00e9rcoles tuvo celebraci\u00f3n del pesebre viviente y la misa criolla"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-21-at-11.54.59.jpeg?fit=1280%2C720&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=87614"}],"version-history":[{"count":1,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87614\/revisions"}],"predecessor-version":[{"id":87619,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87614\/revisions\/87619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/87616"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=87614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=87614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=87614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}