{"id":87630,"date":"2023-12-21T23:21:54","date_gmt":"2023-12-21T23:21:54","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=87630"},"modified":"2023-12-22T02:51:59","modified_gmt":"2023-12-22T02:51:59","slug":"entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/","title":{"rendered":"Entr\u00f3 a la casa de una mujer adulta  y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora"},"content":{"rendered":"\n<p>Siendo aproximadamente las 13:00 horas de la v\u00edspera, personal de la Patrulla Preventivo en calle Costa Rica al 300 procedi\u00f3 a la detenci\u00f3n de un hombre de 29 a\u00f1os de edad por supuesto autor del delito de \u201cRobo\u201d.<\/p>\n\n\n\n<p>Ya que en momentos antes tras recibir un llamado a la l\u00ednea de emergencias 911 que daba cuenta de un hecho de robo que se estaba cometiendo en una vivienda de ese sector, al constituirse personal policial constata junto a la propietaria de la misma, una mujer de 70 a\u00f1os de edad, que luego de violentar la puerta de ingreso le hab\u00edan sustra\u00eddo bienes y pertenencias desde el interior. <\/p>\n\n\n\n<p>Al reunir testimonios de vecinos se logra determinar que lo sucedido era reciente y las caracter\u00edsticas de lo sucedido, por lo que se implementa un Operativo Cerrojo en el que se intercepta a pocas cuadras de all\u00ed un veh\u00edculo de servicio de taxi que transportaba a quien result\u00f3 detenido, llevando un equipo de m\u00fasica, un televisor de 32 pulgadas, un ventilador de pie y una bordeadora el\u00e9ctrica, entre otros.<\/p>\n\n\n\n<p>Se labran actuaciones a disposici\u00f3n de la Fiscal\u00eda de Instrucci\u00f3n de Segundo Turno a cargo de la Dra. Juliana Companys, Prosec. Dr. Jos\u00e9 \u00c1lvarez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siendo aproximadamente las 13:00 horas de la v\u00edspera, personal de la Patrulla Preventivo en calle Costa Rica al 300 procedi\u00f3 a la detenci\u00f3n de un hombre de 29 a\u00f1os de edad por supuesto autor del delito de \u201cRobo\u201d. Ya que en momentos antes tras recibir un llamado a la l\u00ednea de emergencias 911 que daba [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-87630","post","type-post","status-publish","format-standard","hentry","category-sociedad","category-villa-maria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora - El Regional\" \/>\n<meta property=\"og:description\" content=\"Siendo aproximadamente las 13:00 horas de la v\u00edspera, personal de la Patrulla Preventivo en calle Costa Rica al 300 procedi\u00f3 a la detenci\u00f3n de un hombre de 29 a\u00f1os de edad por supuesto autor del delito de \u201cRobo\u201d. Ya que en momentos antes tras recibir un llamado a la l\u00ednea de emergencias 911 que daba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T23:21:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-22T02:51:59+00:00\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora\",\"datePublished\":\"2023-12-21T23:21:54+00:00\",\"dateModified\":\"2023-12-22T02:51:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/\"},\"wordCount\":228,\"commentCount\":0,\"articleSection\":[\"Sociedad\",\"Villa Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/\",\"name\":\"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"datePublished\":\"2023-12-21T23:21:54+00:00\",\"dateModified\":\"2023-12-22T02:51:59+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/","og_locale":"es_ES","og_type":"article","og_title":"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora - El Regional","og_description":"Siendo aproximadamente las 13:00 horas de la v\u00edspera, personal de la Patrulla Preventivo en calle Costa Rica al 300 procedi\u00f3 a la detenci\u00f3n de un hombre de 29 a\u00f1os de edad por supuesto autor del delito de \u201cRobo\u201d. Ya que en momentos antes tras recibir un llamado a la l\u00ednea de emergencias 911 que daba [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-12-21T23:21:54+00:00","article_modified_time":"2023-12-22T02:51:59+00:00","author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora","datePublished":"2023-12-21T23:21:54+00:00","dateModified":"2023-12-22T02:51:59+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/"},"wordCount":228,"commentCount":0,"articleSection":["Sociedad","Villa Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/","name":"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"datePublished":"2023-12-21T23:21:54+00:00","dateModified":"2023-12-22T02:51:59+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/entro-a-la-casa-de-una-mujer-adulta-y-le-robo-su-televisor-equipo-de-musica-y-su-bordeadora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"Entr\u00f3 a la casa de una mujer adulta y le rob\u00f3 su televisor, equipo de m\u00fasica y su bordeadora"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=87630"}],"version-history":[{"count":2,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87630\/revisions"}],"predecessor-version":[{"id":87633,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87630\/revisions\/87633"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=87630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=87630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=87630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}