{"id":87810,"date":"2023-12-27T19:13:52","date_gmt":"2023-12-27T19:13:52","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=87810"},"modified":"2023-12-28T02:38:49","modified_gmt":"2023-12-28T02:38:49","slug":"accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/","title":{"rendered":"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras"},"content":{"rendered":"\n<p>Entre los temas m\u00e1s relevantes, mencion\u00f3 la creaci\u00f3n de la guardia local de prevenci\u00f3n y convivencia, la sanci\u00f3n a quienes arrojen residuos, conduzcan de forma peligrosa y generen ruidos molestos.<\/p>\n\n\n\n<p>En la ma\u00f1ana de hoy, el intendente Eduardo Accastello present\u00f3, en el Concejo Deliberante, diversos proyectos con el objetivo de dar respuesta a problem\u00e1ticas que afectan a los vecinos y vecinas de nuestra ciudad, relacionadas con la seguridad social y el cuidado del medioambiente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.44.jpeg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87812\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.44.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.44.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.44.jpeg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.44.jpeg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.44.jpeg?w=1599&amp;ssl=1 1599w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Es as\u00ed que, Accastello manifest\u00f3: \u201cVamos a adherir a la Ley de Seguridad de la Provincia, para ser de las primeras ciudades que tengan la posibilidad de contar con una guardia local de prevenci\u00f3n y convivencia ciudadana, en sinton\u00eda con las propuestas del gobernador Mart\u00edn Llaryora, para que los municipios grandes como Villa Mar\u00eda puedan tener su propia guardia de prevenci\u00f3n, con sus veh\u00edculos y armamento no letal\u00bb.<\/p>\n\n\n\n<p>\u00abTodo esto apunta a que podamos ser los o\u00eddos y voz de los vecinos y vecinas ante la polic\u00eda, que va a seguir siendo el \u00f3rgano de ejecuci\u00f3n contra el delito, pero tambi\u00e9n como acci\u00f3n preventiva\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>En sinton\u00eda, el mandatario local anunci\u00f3 la intenci\u00f3n de crear una sede de la Fuerza Policial Antinarcotr\u00e1fico (FPA) en nuestra ciudad, junto con un centro de rehabilitaci\u00f3n de adicciones, ya que \u201cuno de los flagelos que existen en Villa Mar\u00eda es la droga, y la polic\u00eda antinarc\u00f3ticos junto al Consejo de Seguridad, nos va a ayudar a buscar paliativos para reparar la inseguridad\u201d, asegur\u00f3 el intendente.<\/p>\n\n\n\n<p>A su vez, la problem\u00e1tica de la venta y consumo de drogas es un tema presente en las agendas barriales, presentado a trav\u00e9s de los Consejos Barriales, constituidos d\u00edas atr\u00e1s en un trabajo conjunto entre el Estado local y el viceministro del Ministerio de Desarrollo Social y Promoci\u00f3n del Empleo de la Provincia, Paulo Cassinerio. Por su parte, a trav\u00e9s de los Centros Vecinales, se plante\u00f3 el inconveniente de las motos y los ruidos molestos, sobre todo en sectores aleda\u00f1os a la Costanera.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.51.jpeg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-87811\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.51.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.51.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.51.jpeg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.51.jpeg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.51.jpeg?w=1599&amp;ssl=1 1599w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>En este sentido, una de las propuestas presentadas ante el Consejo tiene que ver con la ampliaci\u00f3n de los m\u00e9todos v\u00e1lidos para dar inicio al proceso de faltas y las consecuencias que de ellos derivan.<\/p>\n\n\n\n<p>El objetivo es utilizar las c\u00e1maras de seguridad dispuestas en nuestra ciudad a los fines de ejecutar las multas directamente desde el Centro de Monitoreo, en particular sobre aquellos veh\u00edculos que arrojen basura en lugares indebidos, realicen conducci\u00f3n peligrosa o tengan escapes libres. Todo esto, tendr\u00e1 por objetivo \u201cresolver problem\u00e1ticas que afectan a todos los vecinos de la ciudad\u201d, coment\u00f3 Accastello.<\/p>\n\n\n\n<p>Al respecto de las multas, el jefe comunal dijo que estas no ser\u00e1n s\u00f3lo punibles econ\u00f3micamente, sino que se buscar\u00e1 el resarcimiento social a trav\u00e9s del trabajo en plazas o instituciones, para aquellas personas que cometan faltas.<\/p>\n\n\n\n<p>Acompa\u00f1aron al intendente, el presidente del Concejo Deliberante, Juan Pablo Inglese, y los secretarios de Unidad Intendencia, Agust\u00edn Turletti Mino, y de Prevenci\u00f3n, Seguridad y Convivencia Urbana, Guadalupe Vazquez, y el Asesor Letrado, Franco Valzacchi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre los temas m\u00e1s relevantes, mencion\u00f3 la creaci\u00f3n de la guardia local de prevenci\u00f3n y convivencia, la sanci\u00f3n a quienes arrojen residuos, conduzcan de forma peligrosa y generen ruidos molestos. En la ma\u00f1ana de hoy, el intendente Eduardo Accastello present\u00f3, en el Concejo Deliberante, diversos proyectos con el objetivo de dar respuesta a problem\u00e1ticas que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[15302,5,2],"tags":[],"class_list":["post-87810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-sociedad","category-villa-maria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras - El Regional\" \/>\n<meta property=\"og:description\" content=\"Entre los temas m\u00e1s relevantes, mencion\u00f3 la creaci\u00f3n de la guardia local de prevenci\u00f3n y convivencia, la sanci\u00f3n a quienes arrojen residuos, conduzcan de forma peligrosa y generen ruidos molestos. En la ma\u00f1ana de hoy, el intendente Eduardo Accastello present\u00f3, en el Concejo Deliberante, diversos proyectos con el objetivo de dar respuesta a problem\u00e1ticas que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-27T19:13:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T02:38:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras\",\"datePublished\":\"2023-12-27T19:13:52+00:00\",\"dateModified\":\"2023-12-28T02:38:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/\"},\"wordCount\":558,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1\",\"articleSection\":[\"destacado\",\"Sociedad\",\"Villa Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/\",\"name\":\"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1\",\"datePublished\":\"2023-12-27T19:13:52+00:00\",\"dateModified\":\"2023-12-28T02:38:49+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1\",\"width\":1599,\"height\":899},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/","og_locale":"es_ES","og_type":"article","og_title":"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras - El Regional","og_description":"Entre los temas m\u00e1s relevantes, mencion\u00f3 la creaci\u00f3n de la guardia local de prevenci\u00f3n y convivencia, la sanci\u00f3n a quienes arrojen residuos, conduzcan de forma peligrosa y generen ruidos molestos. En la ma\u00f1ana de hoy, el intendente Eduardo Accastello present\u00f3, en el Concejo Deliberante, diversos proyectos con el objetivo de dar respuesta a problem\u00e1ticas que [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-12-27T19:13:52+00:00","article_modified_time":"2023-12-28T02:38:49+00:00","og_image":[{"width":1599,"height":899,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg","type":"image\/jpeg"}],"author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras","datePublished":"2023-12-27T19:13:52+00:00","dateModified":"2023-12-28T02:38:49+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/"},"wordCount":558,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1","articleSection":["destacado","Sociedad","Villa Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/","name":"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1","datePublished":"2023-12-27T19:13:52+00:00","dateModified":"2023-12-28T02:38:49+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1","width":1599,"height":899},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/accastello-presento-personalmente-proyectos-para-mejorar-la-seguridad-en-la-ciudad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"Accastello present\u00f3 proyectos para mejorar la seguridad: Guardia Urbana y multas a trav\u00e9s de c\u00e1maras"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-27-at-14.31.35.jpeg?fit=1599%2C899&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=87810"}],"version-history":[{"count":2,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87810\/revisions"}],"predecessor-version":[{"id":87849,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87810\/revisions\/87849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/87813"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=87810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=87810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=87810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}