{"id":87918,"date":"2023-12-29T20:00:37","date_gmt":"2023-12-29T20:00:37","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=87918"},"modified":"2023-12-29T20:00:54","modified_gmt":"2023-12-29T20:00:54","slug":"como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/","title":{"rendered":"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas"},"content":{"rendered":"\n<p>Hace unos dias el municipio inici\u00f3 la campa\u00f1a de lucha contra el Dengue. Ahora, con casos importados detectados en la ciudad se intensificaron las iniciativas y se pusieron en marcha protocolos. En ese sentido, el Municipio puso en marcha una serie de acciones preventivas lideradas por la Subsecretar\u00eda de Desarrollo Productivo.<\/p>\n\n\n\n<p>Durante la madrugada de hoy, las tareas de fumigaci\u00f3n dieron inicio en la Costanera, desde el Puente Brigadier Juan Bautista Bustos hasta el balneario Puerto Madero.<\/p>\n\n\n\n<p>Ma\u00f1ana, las labores ser\u00e1n reiteradas en la misma zona, extendi\u00e9ndose luego a las periferias de la ciudad. En paralelo, el Municipio lleva a cabo labores de descachareo y corte de pasto en distintas \u00e1reas, como parte de un enfoque integral para combatir la proliferaci\u00f3n del mosquito Aedes aegypti, transmisor del Dengue.<\/p>\n\n\n\n<p>En este contexto, se hace un llamado a la comunidad para que, despu\u00e9s de d\u00edas de lluvia, revisen sus patios en busca de objetos que puedan acumular agua, ya que estos suelen ser lugares propicios para la propagaci\u00f3n de larvas.<\/p>\n\n\n\n<p>Se recomienda el cambio diario de agua de recipientes, floreros o plantas; tapar o voltear objetos que acumulen agua y desechar los que no se utilicen; limpiar peri\u00f3dicamente tanques de agua, canaletas, rejillas, piscinas, desag\u00fces y otros objetos; colocar telas mosquiteras en puertas y ventanas; usar repelente con la frecuencia indicada; vestir mangas largas y pantalones largos de colores claros para evitar picaduras.<\/p>\n\n\n\n<p>Adem\u00e1s, es oportuno recordar los s\u00edntomas a tener en cuenta, entre los que se destacan fiebre, dolor de cabeza, dolores musculares o de articulaciones, erupci\u00f3n o manchas en la piel, enrojecimiento de ojos, entre otros. Ante la presencia de cualquiera de estos s\u00edntomas, se insta a la poblaci\u00f3n a acudir al centro de salud m\u00e1s cercano y evitar la automedicaci\u00f3n, especialmente la toma de aspirina o ibuprofeno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos dias el municipio inici\u00f3 la campa\u00f1a de lucha contra el Dengue. Ahora, con casos importados detectados en la ciudad se intensificaron las iniciativas y se pusieron en marcha protocolos. En ese sentido, el Municipio puso en marcha una serie de acciones preventivas lideradas por la Subsecretar\u00eda de Desarrollo Productivo. Durante la madrugada de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[15302,5,2],"tags":[],"class_list":["post-87918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-sociedad","category-villa-maria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas - El Regional\" \/>\n<meta property=\"og:description\" content=\"Hace unos dias el municipio inici\u00f3 la campa\u00f1a de lucha contra el Dengue. Ahora, con casos importados detectados en la ciudad se intensificaron las iniciativas y se pusieron en marcha protocolos. En ese sentido, el Municipio puso en marcha una serie de acciones preventivas lideradas por la Subsecretar\u00eda de Desarrollo Productivo. Durante la madrugada de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-29T20:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-29T20:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1204\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas\",\"datePublished\":\"2023-12-29T20:00:37+00:00\",\"dateModified\":\"2023-12-29T20:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/\"},\"wordCount\":339,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1\",\"articleSection\":[\"destacado\",\"Sociedad\",\"Villa Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/\",\"name\":\"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1\",\"datePublished\":\"2023-12-29T20:00:37+00:00\",\"dateModified\":\"2023-12-29T20:00:54+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1\",\"width\":1204,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/","og_locale":"es_ES","og_type":"article","og_title":"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas - El Regional","og_description":"Hace unos dias el municipio inici\u00f3 la campa\u00f1a de lucha contra el Dengue. Ahora, con casos importados detectados en la ciudad se intensificaron las iniciativas y se pusieron en marcha protocolos. En ese sentido, el Municipio puso en marcha una serie de acciones preventivas lideradas por la Subsecretar\u00eda de Desarrollo Productivo. Durante la madrugada de [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2023-12-29T20:00:37+00:00","article_modified_time":"2023-12-29T20:00:54+00:00","og_image":[{"width":1204,"height":1600,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg","type":"image\/jpeg"}],"author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas","datePublished":"2023-12-29T20:00:37+00:00","dateModified":"2023-12-29T20:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/"},"wordCount":339,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1","articleSection":["destacado","Sociedad","Villa Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/","name":"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1","datePublished":"2023-12-29T20:00:37+00:00","dateModified":"2023-12-29T20:00:54+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1","width":1204,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/como-parte-de-la-campana-de-lucha-contra-el-dengue-en-la-ciudad-se-intensifica-la-fumigacion-y-acciones-preventivas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"Como parte de la campa\u00f1a de lucha contra el Dengue en la ciudad, se intensifica la fumigaci\u00f3n y acciones preventivas"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-29-at-14.20.57.jpeg?fit=1204%2C1600&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=87918"}],"version-history":[{"count":1,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87918\/revisions"}],"predecessor-version":[{"id":87920,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/87918\/revisions\/87920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/87919"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=87918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=87918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=87918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}