{"id":88887,"date":"2024-01-22T23:40:46","date_gmt":"2024-01-22T23:40:46","guid":{"rendered":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?p=88887"},"modified":"2024-01-29T17:42:24","modified_gmt":"2024-01-29T17:42:24","slug":"la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes","status":"publish","type":"post","link":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/","title":{"rendered":"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>El accidente del vuelo 571, m\u00e1quina Fairchild Hiller FH-227, de la Fuerza A\u00e9rea Uruguaya, conocido popularmente como el \u201cMilagro de Los Andes\u201d o \u201cTragedia de Los Andes\u201d, ocurri\u00f3 el viernes 13 de octubre de 1972. Junto con los sobrevivientes, hubo una figura que tuvo un rol destacado, aunque de alg\u00fan modo, algo olvidado, el arriero que recibi\u00f3 el mensaje de Nando y avis\u00f3 a las autoridades.<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Escribe: Julio A. Ben\u00edtez \u2013 <a href=\"mailto:benitezjulioalberto@gmail.com\">benitezjulioalberto@gmail.com<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cVengo de un avi\u00f3n que cay\u00f3 en las monta\u00f1as. Soy uruguayo. En el avi\u00f3n quedan 14 personas heridas. \u00bfCu\u00e1ndo nos van a buscar arriba?\u201d. La letra titubeante de Fernando \u00abNando\u00bb Parrado, uno de los j\u00f3venes rugbiers que sobrevivi\u00f3 72 d\u00edas entre la nieve perpetua y el fr\u00edo lacerante de la cordillera de los Andes, lleg\u00f3 a manos de un arriero analfabeto.<\/p>\n\n\n\n<p>Con toda prisa recurri\u00f3 a las autoridades, que incr\u00e9dulas organizaron las tareas de rescate. Junto con Roberto Canessa, tras 10 d\u00edas de extenuantes caminatas para buscar la salvaci\u00f3n, desorientados en medio de la nada blanca, lograron cruzar por encima de un r\u00edo el mensaje en un papel atado a una piedra.<\/p>\n\n\n\n<p>Fue el principio de una nueva vida. Se salvar\u00edan 16 de los 45 pasajeros del avi\u00f3n de la fuerza a\u00e9rea, la mayor\u00eda miembros del equipo de rugby del club de exalumnos del Colegio Stella Maris de Montevideo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/catalan-arriero-los-andes-card.jpg?resize=1000%2C563&#038;ssl=1\" alt=\"\" class=\"wp-image-28774\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/catalan-arriero-los-andes-card.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/catalan-arriero-los-andes-card.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/catalan-arriero-los-andes-card.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>El arriero que permiti\u00f3 salvarles las vidas, con dos de los sobrevivientes. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>El accidente del vuelo 571, m\u00e1quina Fairchild Hiller FH-227, de la Fuerza A\u00e9rea Uruguaya, conocido popularmente como el \u201cMilagro de Los Andes\u201d o \u201cTragedia de Los Andes\u201d, ocurri\u00f3 el viernes 13 de octubre de 1972.<\/p>\n\n\n\n<p>El avi\u00f3n que conduc\u00eda al equipo de rugby del Old Christians, integrado por alumnos del Colegio uruguayo Stella Maris, se estrell\u00f3 en un risco de la cordillera en Mendoza a 3.600 metros de altura, en ruta hacia Santiago de Chile, en momentos en que se desarrollaba un frente de inestabilidad en todo el sector de la cordillera central.<\/p>\n\n\n\n<p>Al mando del aparato estaban el coronel Julio C\u00e9sar Ferradas y su copiloto el teniente coronel Dante Lagurara. Completaban la tripulaci\u00f3n el teniente Ram\u00f3n Sa\u00fal Mart\u00ednez, Ovidio Ram\u00edrez y el mec\u00e1nico Carlos Roque.<\/p>\n\n\n\n<p>Este tipo de avi\u00f3n tiene la particularidad de volar con la cola m\u00e1s baja que la nariz, como el vuelo de un ganso y tiene su techo de vuelo hasta 6.800 metros a una velocidad de 437 km\/h.<\/p>\n\n\n\n<p><strong>El comienzo<\/strong><\/p>\n\n\n\n<p>El mal tiempo hab\u00eda obligado al piloto a detenerse en el aeropuerto El Plumerillo (Mendoza) donde pasaron la noche y el vuelo continu\u00f3 despegando a las 14.18 hora local, con destino a Santiago de Chile.<\/p>\n\n\n\n<p>La ruta a seguir era por Paso del Planch\u00f3n entre las ciudades de Malarg\u00fce y Curic\u00f3 (Chile). El avi\u00f3n ascendi\u00f3 hasta los 6.000 msnm volando en direcci\u00f3n sur manteniendo a la cordillera a su derecha y con viento de cola de 20 a 60 nudos.<\/p>\n\n\n\n<p>A las 15.08 comunicaron su posici\u00f3n a la estaci\u00f3n de control de Malarg\u00fce, girando en direcci\u00f3n noroeste hasta volar por la ruta a\u00e9rea G17 sobre la cordillera. Lagurara&nbsp; estim\u00f3 que alcanzar\u00edan el Paso del Planch\u00f3n -el punto de las monta\u00f1as donde se pasaba del control de tr\u00e1nsito a\u00e9reo de Mendoza al de Santiago\u2013 a las 15.21 horas. Un mar de nubes blancas se extend\u00eda por debajo de ellos.<\/p>\n\n\n\n<p>Todo iba bien, sin embargo, hubo un cambio de suma importancia: la direcci\u00f3n y sentido de los vientos cambiaron de modo que el avi\u00f3n pudo ver reducida su velocidad de crucero en un 15%, de 210 a 180 nudos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"666\" height=\"456\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-imagen-real-tragedia-andes.jpg?resize=666%2C456&#038;ssl=1\" alt=\"\" class=\"wp-image-88893\" style=\"width:910px;height:auto\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-imagen-real-tragedia-andes.jpg?w=666&amp;ssl=1 666w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-imagen-real-tragedia-andes.jpg?resize=300%2C205&amp;ssl=1 300w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/><figcaption class=\"wp-element-caption\"><em>Una imagen real de la tragedia en la helada monta\u00f1a de los Andes. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Aparentemente no se consider\u00f3 esta crucial variable y se cometi\u00f3 un error de navegaci\u00f3n, que provoc\u00f3 que estuvieran m\u00e1s al norte y m\u00e1s al este de lo que pensaban, y dado que el paso estaba cubierto por nubes, los pilotos estimaron en base al tiempo habitual empleado para cruzar el mismo.<\/p>\n\n\n\n<p>Sin embargo, no tuvieron en cuenta los fuertes vientos en contra que desaceleraron el avi\u00f3n y el consiguiente aumento de tiempo necesario para completar la traves\u00eda.<\/p>\n\n\n\n<p>A las 15.21 Lagurara inform\u00f3 al control de Santiago de Chile que sobrevolaban el Paso del Planch\u00f3n, calculando llegar a Curic\u00f3 a las 15.32, cuando en realidad sobrevolaban la cordillera a la altura de San Fernando, aproximadamente 50 kil\u00f3metros al norte y con monta\u00f1as de mayores alturas.<\/p>\n\n\n\n<p>Unos tres minutos m\u00e1s tarde, el Fairchild comunic\u00f3 de nuevo a Santiago que ya divisaban Curic\u00f3. El avi\u00f3n entonces vir\u00f3 a rumbo norte, aproximadamente 70-100 km. antes de la ruta hacia el aeropuerto de Pudahuel.<\/p>\n\n\n\n<p>La torre de control de Santiago dio por buena la posici\u00f3n comunicada por el piloto, autoriz\u00e1ndole&nbsp; a descender a 3.500 msnm, dando por hecho que descender\u00eda en Pudahuel, al oeste de Santiago, cuando en realidad se adentraban en los encajonamientos de la cordillera en medio de los cordones monta\u00f1osos, sobrevolando el l\u00edmite argentino-chileno y en las inmediaciones del volc\u00e1n Tinguiririca de la provincia de Colchagua. Dicho error de m\u00e1s de 100 km. dificult\u00f3 posteriormente las tareas de b\u00fasqueda de rescate.<\/p>\n\n\n\n<p>Contando con autorizaci\u00f3n, el avi\u00f3n, con un techo bajo de nubes, comenz\u00f3 el descenso apoyado por instrumentos entre la niebla de una tormenta en desarrollo mientras todav\u00eda se encontraban entre las monta\u00f1as.<\/p>\n\n\n\n<p>Descendi\u00f3 a 1.000 metros y all\u00ed el aparato entr\u00f3 en una nube y comenz\u00f3 a dar sacudidas. Volvi\u00f3 a descender unos cientos de metros m\u00e1s, de golpe, al atravesar varios pozos de aire. Ante la situaci\u00f3n, algunos pasajeros de cabina hicieron chistes sobre el incidente. No falt\u00f3 quien alzara los brazos y vitoreara como en una monta\u00f1a rusa, incluso jugando con un bal\u00f3n de rugby.<\/p>\n\n\n\n<p>La serie de descensos bruscos continuados hicieron que el avi\u00f3n perdiera m\u00e1s altitud (casi 1.500 m.), momentos en que los pasajeros quedaron estupefactos al ver que el ala del avi\u00f3n estaba muy cerca de las monta\u00f1as y dudaron de que si aquello era normal, y unos momentos despu\u00e9s, los pasajeros se miraban unos a otros con terror, mientras otros rezaban esperando el inevitable desenlace de la situaci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/la-sociedad-de-la-nieve-tragedia-andes.jpg?resize=1024%2C683&#038;ssl=1\" alt=\"\" class=\"wp-image-88889\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/la-sociedad-de-la-nieve-tragedia-andes.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/la-sociedad-de-la-nieve-tragedia-andes.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/la-sociedad-de-la-nieve-tragedia-andes.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/la-sociedad-de-la-nieve-tragedia-andes.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Im\u00e1genes de la tragedia: una es real y la otra pertenece al filme de Netflix. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>El aparato descendi\u00f3 m\u00e1s a\u00fan y se meti\u00f3 en un largo caj\u00f3n de unos 12 km. de elevadas cimas en medio de una nube que repentinamente se abri\u00f3 al tiempo que los pilotos vieron como el aeroplano estaba en rumbo frontal de colisi\u00f3n, con la parte final del caj\u00f3n, cerrado por un alto risco, colindante con el cerro Soler.<\/p>\n\n\n\n<p><strong>Alarma y terror<\/strong><\/p>\n\n\n\n<p>La alarma sonora de colisi\u00f3n dentro de la cabina se activ\u00f3, lo que aterr\u00f3 a los pasajeros y tripulaci\u00f3n. Lagurara, desesperadamente, desvi\u00f3 el avi\u00f3n enfilando levemente al noroeste hacia estribor enfrentando la parte que aparentemente parec\u00eda m\u00e1s baja de los fallarones, acelerando y jalando a fondo los controles de los planos para tomar altura y se enfrent\u00f3 a una cumbre de 4.400 msnm que a duras penas y mediante un extraordinario sobresfuerzo f\u00edsico pudo evitar la colisi\u00f3n frontal y salvar la nariz del aparato por apenas un par de metros, pero golpe\u00f3 la cola en la orilla de la cumbre en un pico sin nombre, situado entre el cerro El Sosneado y el volc\u00e1n Tinguiririca, en el lado argentino de la frontera Argentina-Chile.<\/p>\n\n\n\n<p>Por segunda vez, el aparato golpe\u00f3 un risco de 4.200 msnm perdiendo el ala derecha, que fue lanzada hacia atr\u00e1s con tal fuerza que cort\u00f3 la cola del aparato a la altura de la ventanilla N\u00ba 8 de 10 por el lado de babor y N\u00ba 7 por el lado de estribor.<\/p>\n\n\n\n<p>Al desprenderse la cola con el estabilizador vertical, qued\u00f3 abierto un boquete tras de s\u00ed en la parte posterior del fuselaje. En este desprendimiento, se descolgaron al menos dos filas de asientos que salieron volando al vac\u00edo: murieron cinco personas que estaban con los cinturones puestos.<\/p>\n\n\n\n<p>Al golpear por tercera vez en otro pico, perdi\u00f3 el ala izquierda, quedando en vuelo \u00fanicamente su fuselaje, a manera de un proyectil y que a\u00fan con velocidad golpe\u00f3 tangencialmente el terreno nevado y resbal\u00f3 por una amplia ladera nevada y empinada de m\u00e1s de 1 km. de largo, dando una curva en su descenso hasta detenerse golpeando en un banco de nieve, momento en que dos pasajeros m\u00e1s murieron, atados a sus asientos, al ser despedidos por el boquete posterior.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"412\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas.jpg?resize=680%2C412&#038;ssl=1\" alt=\"\" class=\"wp-image-88894\" style=\"width:910px;height:auto\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas.jpg?w=680&amp;ssl=1 680w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas.jpg?resize=300%2C182&amp;ssl=1 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><em>Otra postal de uno de los filmes m\u00e1s vistos en las \u00faltimas semanas. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>El sitio donde qued\u00f3 el avi\u00f3n es una pendiente de los Andes que mira al este, a 3.600 msnm, en el glaciar de Las L\u00e1grimas, en la alta cuenca del r\u00edo Atuel, provincia de Mendoza, en el centro-oeste de Argentina; se ubica en el distrito Malarg\u00fce, muy pr\u00f3ximo al l\u00edmite con el distrito El Sosneado, en el departamento San Rafael, a 1.200 m. de la frontera argentina-chilena, pero a mucha menor altitud, pues la frontera alcanza all\u00ed alturas de hasta 4.770 msnm.<\/p>\n\n\n\n<p><strong>Impacto y muerte<\/strong><\/p>\n\n\n\n<p>El golpe de la nariz del avi\u00f3n contra el banco de nieve result\u00f3 fatal para los tripulantes de cabina, primero que la cabeza del piloto azotara contra el bast\u00f3n de control que le ocasion\u00f3 la muerte instant\u00e1nea y el tren de aterrizaje delantero se desplazara hacia atr\u00e1s comprimiendo fuertemente la cabina del avi\u00f3n, atrapando a los pilotos contra el panel de instrumentos.<\/p>\n\n\n\n<p>Lagurara qued\u00f3 con su cabeza fuera de la ventanilla y con su pecho y cuerpo comprimido y atrapado contra el fuselaje. Los pasajeros que quedaron dentro, por la inercia, fueron comprimidos en sus asientos hacia la parte frontal del fuselaje, que se elev\u00f3 hasta casi tocar el techo. La misma inercia hizo que los asientos se soltaran de sus bases y atraparan a muchos por las piernas, la mayor\u00eda muri\u00f3.<\/p>\n\n\n\n<p>Otros sufrieron traumatismo cr\u00e1neo encef\u00e1lico, lo que provoc\u00f3 su muerte, mientras que otros quedaron atrapados en sus asientos sin posibilidad de zafarse. Para el resto, el golpe fue amortiguado, que incre\u00edblemente&nbsp; algunos resultaron ilesos o con tan poco heridas leves. Otros sufrieron heridas internas graves y fallecieron en horas posteriores. De inmediato, Marcelo P\u00e9rez, el capit\u00e1n del equipo de rugby organiz\u00f3 a los ilesos para ayudar a liberar a los que segu\u00edan atrapados y los heridos, despejando el fuselaje para prepararse para la noche. Uno de los supervivientes sali\u00f3 por el atr\u00e1s del fuselaje y a tientas entre la nieve y el fuselaje se acerc\u00f3 al piloto agonizante, que le pidi\u00f3 agua y le acerc\u00f3 nieve a la boca, cuando empez\u00f3 a decir: \u201cAnot\u00e1, estamos en Curic\u00f3, anot\u00e1\u2026\u201d y le pidi\u00f3 que le pegara un tiro con el rev\u00f3lver que estaba en la cabina, cosa que no ocurri\u00f3 y falleci\u00f3 congelado tras agonizar toda la noche.<\/p>\n\n\n\n<p>De las 45 personas, 13 murieron en el accidente o poco despu\u00e9s, 4 fallecieron a la ma\u00f1ana siguiente y el octavo d\u00eda muri\u00f3 Susana Parrado, hermana de Fernando, un sobreviviente.<\/p>\n\n\n\n<p><strong>La supervivencia<\/strong><\/p>\n\n\n\n<p>Los 27 restantes tuvieron que enfrentarse a duras condiciones ambientales y clim\u00e1ticas con temperaturas entre 25 \u00ba a 42 \u00ba bajo cero. Durante varios d\u00edas, las partidas de rescate intentaron localizar los restos del avi\u00f3n sin \u00e9xito, incluso algunos aviones estuvieron cerca del lugar, pero sobrevolando a mucha altura como para poder verlos.<\/p>\n\n\n\n<p>Muchos de los supervivientes hab\u00edan sufrido diversas lesiones cortantes o moretones y carec\u00edan de calzado y ropa adecuada para el fr\u00edo y se organizaron para resistir las duras condiciones imperantes, empezando por fabricar elementos y utensilios ingeniosos tales como alambiques, guantes (con los forros de los asientos), botas (con los cojines de los mismos) para evitar hundirse en la nieve al querer salir y anteojos (con pl\u00e1stico tintado) para resistir al encandilamiento originado por la nieve.<\/p>\n\n\n\n<p>La mayor\u00eda dorm\u00eda con un par de pantalones, tres o cuatro su\u00e9teres, tres pares de calcetines y algunos se tapaban la cabeza con una camisa para conservar el aliento. Para evitar la hipotermia, en las noches m\u00e1s fr\u00edas, se daban masajes para reactivar la circulaci\u00f3n e intentaban mantener la temperatura corporal en contacto entre s\u00ed.<\/p>\n\n\n\n<p>Algunos prefer\u00edan dormir descalzos para evitar golpear a alguien con sus zapatos. En el und\u00e9cimo d\u00eda, escucharon por una radio a pila, con consternaci\u00f3n, que se hab\u00eda abandonado la b\u00fasqueda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-tragedia-andes.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-88891\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-tragedia-andes.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-tragedia-andes.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-tragedia-andes.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-tragedia-andes.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Una de las im\u00e1genes m\u00e1s difundidas de \u00abLa Sociedad de la Nieve\u00bb. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>El alud<\/strong><\/p>\n\n\n\n<p>La noche del 29 de octubre, a 16 d\u00edas de la ca\u00edda, una nueva tragedia se cerni\u00f3 sobre el resto del avi\u00f3n y sus ocupantes. A eso de las 23 horas un alud se desliz\u00f3 y sepult\u00f3 los restos del fuselaje, entrando por el boquete de la parte posterior, arrasando el muro provisional que hab\u00edan fabricado, sepultando a quienes dorm\u00edan en su interior, salvo un joven.<\/p>\n\n\n\n<p>Roy Harley desesperadamente comenz\u00f3 a cavar en busca de los que yac\u00edan bajo la nieve, pero pese a los desesperados esfuerzos, 8 personas murieron asfixiadas, incluyendo al capit\u00e1n del equipo, Marcelo P\u00e9rez, y la \u00faltima pasajera de sexo femenino, Liliana Navarro de Methol.<\/p>\n\n\n\n<p>Las condiciones de supervivencia se endurecieron a\u00fan m\u00e1s, apenas dispon\u00edan de espacio en el interior, contando con menos de un metro hasta el techo, solo en la parte delantera del fuselaje. Se percataron suficientemente a tiempo de la carencia de ox\u00edgeno al ver que la llama de un mechero tend\u00eda a pagarse. Nano Parrado localiz\u00f3 una vara con la que golpe\u00f3 el techo del fuselaje hasta conseguir hacer un agujero, pero la capa de nieve por encima del fuselaje le oblig\u00f3 a seguir perforando hasta llegar a la superficie por donde finalmente entr\u00f3 el ox\u00edgeno necesario.<\/p>\n\n\n\n<p><strong>Alimentarse de carne humana<\/strong><\/p>\n\n\n\n<p>Pod\u00edan sentir c\u00f3mo en el exterior se estaba desarrollando un duro temporal, sin embargo, carec\u00edan del alimento que almacenaban fuera del fuselaje. Esto les oblig\u00f3 a hacer uso de alguno de los cuerpos de sus compa\u00f1eros fallecidos en el alud que se encontraban en el interior.<\/p>\n\n\n\n<p>Este hecho les condicion\u00f3 de tal modo que posteriormente reubicar\u00edan los cuerpos, tendiendo en cierta medida a dispersarlos pensando que as\u00ed facilitar\u00edan m\u00e1s su disponibilidad ante situaciones inadvertidas.<\/p>\n\n\n\n<p>A mediados de noviembre, fallecieron Arturo Nogueira y Rafael Echeverren, a causa de gangrena, y el 11 de diciembre morir\u00eda la \u00faltima v\u00edctima del accidente, Numa Turcatti, por la misma causa.<\/p>\n\n\n\n<p>El grupo sobrevivi\u00f3 durante 72 d\u00edas y no muri\u00f3 de inanici\u00f3n gracias a la decisi\u00f3n grupal de alimentarse de la carne de sus compa\u00f1eros muertos que estaban enterrados afuera. No fue una decisi\u00f3n f\u00e1cil de tomar y en un principio algunos se opusieron, pero bien pronto comprendieron que era la \u00fanica esperanza de sobrevivir, imponi\u00e9ndose la regla de no utilizar como alimento a ning\u00fan familiar ni tampoco a fallecido del sexo femenino.<\/p>\n\n\n\n<p><strong>Buscando ayuda<\/strong><\/p>\n\n\n\n<p>En algunos momentos, comenz\u00f3 el deshielo que dej\u00f3 al descubierto el fuselaje y los supervivientes pudieron disfrutar de d\u00edas soleados, que fue cuando Nando Parrado, Roberto Canessa y Antonio Vizint\u00edn salieron en busca de ayuda.<\/p>\n\n\n\n<p>Ellos pensaban que estaban en territorio chileno y tomaron la errada decisi\u00f3n de tomar rumbo al oeste. Si la marcha la hubiesen realizado hacia el este, en pocos d\u00edas podr\u00edan haber llegado a lugares m\u00e1s bajos, donde seguro aparecer\u00edan pastores cuidando sus reba\u00f1os, ya en el lado argentino.<\/p>\n\n\n\n<p>Al tercer d\u00eda se tuvo que volver Vizint\u00edn, que hab\u00eda resbalado y se produjo una lesi\u00f3n que no le permit\u00eda seguir caminando. Diez d\u00edas despu\u00e9s de partir de los restos del fuselaje y habiendo caminado aproximadamente unos 59 km. Canesa comenz\u00f3 a sentirse enfermo por lo que Nando debe llevar las dos mochilas, mientras la carne que llevaban hab\u00eda comenzado a descomponerse debido al aumento de temperatura.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"958\" height=\"596\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/Tragedia-de-los-Andes-Avion.jpeg?resize=958%2C596&#038;ssl=1\" alt=\"\" class=\"wp-image-28780\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/Tragedia-de-los-Andes-Avion.jpeg?w=958&amp;ssl=1 958w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/Tragedia-de-los-Andes-Avion.jpeg?resize=300%2C187&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2020\/12\/Tragedia-de-los-Andes-Avion.jpeg?resize=768%2C478&amp;ssl=1 768w\" sizes=\"(max-width: 958px) 100vw, 958px\" \/><figcaption class=\"wp-element-caption\"><em>El avi\u00f3n destrozado en el que viajaban los deportistas uruguayos. <\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Arriero salvador<\/strong><\/p>\n\n\n\n<p>Al amanecer del d\u00eda siguiente ven en la otra orilla de un r\u00edo, a una persona, con quien se quieren comunicar, pero el ruido del agua no permit\u00eda escucharlos.<\/p>\n\n\n\n<p>El hombre, un arriero, inteligentemente at\u00f3 unas hojas con un l\u00e1piz a una piedra y lo arroj\u00f3 a la orilla donde estaban los dos hombres. Nando, a duras penas pudo escribir qui\u00e9nes eran y que estaban buscando ayuda y le devolvi\u00f3 de la misma forma el mensaje.<\/p>\n\n\n\n<p>El hombre, que en ese momento ten\u00eda 44 a\u00f1os, era don Sergio Hilario Catal\u00e1n Mart\u00ednez, arriero que siempre andaba por esos lugares buscando su ganado para llevarlo a su campo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2021\/06\/tragedia-andes-arriero-sobrevivientes.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-39128\" srcset=\"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2021\/06\/tragedia-andes-arriero-sobrevivientes.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2021\/06\/tragedia-andes-arriero-sobrevivientes.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2021\/06\/tragedia-andes-arriero-sobrevivientes.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2021\/06\/tragedia-andes-arriero-sobrevivientes.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Inmediatamente se dirigi\u00f3 a buscar auxilio, ante algunas dudas de quienes le escuchaban su relato a pesar del desprolijo mensaje.<\/p>\n\n\n\n<p>No es necesario seguir detallando lo que fue la noticia \u00a1VIVEN! Despu\u00e9s de haber sido dados como desaparecidos volvieron a la vida los 16 sobrevivientes.<\/p>\n\n\n\n<p>Y fue don Sergio el hombre que pas\u00f3 tambi\u00e9n a la historia por su r\u00e1pida reacci\u00f3n, quien falleci\u00f3 a los 91 a\u00f1os el pasado 11 de febrero de 2020.<\/p>\n\n\n\n<p>Hoy, como hace tiempo fue el filme \u00abViven\u00bb, la pel\u00edcula \u00abLa Sociedad de la Nieve\u00bb cuenta los pormenores de esa tragedia que dej\u00f3 dolor, sufrimiento, pero tambi\u00e9n esp\u00edritu de equipo y una capacidad de sobreponerse a la adversidad como nunca se hab\u00eda visto. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"La sociedad de la nieve | Tr\u00e1iler oficial | Netflix\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/l9tP4M8URhQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Tambi\u00e9n pod\u00e9s ver: <\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-el-regional wp-block-embed-el-regional\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"NDLLvuHXVg\"><a href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/rescates-milagrosos-historias-de-fe-valentia-y-esperanza\/\">Rescates milagrosos: historias de fe, valent\u00eda y esperanza<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abRescates milagrosos: historias de fe, valent\u00eda y esperanza\u00bb \u2014 El Regional\" src=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/rescates-milagrosos-historias-de-fe-valentia-y-esperanza\/embed\/#?secret=2XfbSX6Ygh#?secret=NDLLvuHXVg\" data-secret=\"NDLLvuHXVg\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Fuentes: Wikipedia, El Regional, diversas publicaciones en Internet<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El accidente del vuelo 571, m\u00e1quina Fairchild Hiller FH-227, de la Fuerza A\u00e9rea Uruguaya, conocido popularmente como el \u201cMilagro de Los Andes\u201d o \u201cTragedia de Los Andes\u201d, ocurri\u00f3 el viernes 13 de octubre de 1972. Junto con los sobrevivientes, hubo una figura que tuvo un rol destacado, aunque de alg\u00fan modo, algo olvidado, el arriero [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":88892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[2098,3557,2074],"tags":[5794,4657,23414,8058,7017,23412,13369,9756,23413,5795,348,5793,23416,23415],"class_list":["post-88887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias","category-tercera","category-videos","tag-arriero","tag-avion","tag-canibalismo","tag-cordillera-de-los-andes","tag-heroe","tag-nando-parrado","tag-olvido","tag-pelicula","tag-sociedad-de-la-nieve","tag-supervivencia","tag-tragedia","tag-tragedia-de-los-andes","tag-uruguayos","tag-viven"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes - El Regional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes - El Regional\" \/>\n<meta property=\"og:description\" content=\"El accidente del vuelo 571, m\u00e1quina Fairchild Hiller FH-227, de la Fuerza A\u00e9rea Uruguaya, conocido popularmente como el \u201cMilagro de Los Andes\u201d o \u201cTragedia de Los Andes\u201d, ocurri\u00f3 el viernes 13 de octubre de 1972. Junto con los sobrevivientes, hubo una figura que tuvo un rol destacado, aunque de alg\u00fan modo, algo olvidado, el arriero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/\" \/>\n<meta property=\"og:site_name\" content=\"El Regional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elregionalvm\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T23:40:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T17:42:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1130\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Contenidos El Regional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:site\" content=\"@elregionalvm1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contenidos El Regional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/\"},\"author\":{\"name\":\"Contenidos El Regional\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"headline\":\"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes\",\"datePublished\":\"2024-01-22T23:40:46+00:00\",\"dateModified\":\"2024-01-29T17:42:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/\"},\"wordCount\":3004,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1\",\"keywords\":[\"Arriero\",\"Avi\u00f3n\",\"canibalismo\",\"Cordillera de los Andes\",\"H\u00e9roe\",\"Nando Parrado\",\"olvido\",\"pel\u00edcula\",\"sociedad de la nieve\",\"Supervivencia\",\"tragedia\",\"Tragedia de los Andes\",\"uruguayos\",\"viven\"],\"articleSection\":[\"Historias\",\"tercera\",\"Videos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/\",\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/\",\"name\":\"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes - El Regional\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1\",\"datePublished\":\"2024-01-22T23:40:46+00:00\",\"dateModified\":\"2024-01-29T17:42:24+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1\",\"width\":1130,\"height\":636},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#website\",\"url\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/\",\"name\":\"El Regional\",\"description\":\"Mucho m\u00e1s que informaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/#\\\/schema\\\/person\\\/a0fb9c422317faca23d50163151bc354\",\"name\":\"Contenidos El Regional\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g\",\"caption\":\"Contenidos El Regional\"},\"url\":\"https:\\\/\\\/elregionalvm.com.ar\\\/noticias-villa-maria\\\/author\\\/contenido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes - El Regional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes - El Regional","og_description":"El accidente del vuelo 571, m\u00e1quina Fairchild Hiller FH-227, de la Fuerza A\u00e9rea Uruguaya, conocido popularmente como el \u201cMilagro de Los Andes\u201d o \u201cTragedia de Los Andes\u201d, ocurri\u00f3 el viernes 13 de octubre de 1972. Junto con los sobrevivientes, hubo una figura que tuvo un rol destacado, aunque de alg\u00fan modo, algo olvidado, el arriero [&hellip;]","og_url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/","og_site_name":"El Regional","article_publisher":"https:\/\/www.facebook.com\/elregionalvm","article_published_time":"2024-01-22T23:40:46+00:00","article_modified_time":"2024-01-29T17:42:24+00:00","og_image":[{"width":1130,"height":636,"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg","type":"image\/jpeg"}],"author":"Contenidos El Regional","twitter_card":"summary_large_image","twitter_creator":"@elregionalvm1","twitter_site":"@elregionalvm1","twitter_misc":{"Escrito por":"Contenidos El Regional","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#article","isPartOf":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/"},"author":{"name":"Contenidos El Regional","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"headline":"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes","datePublished":"2024-01-22T23:40:46+00:00","dateModified":"2024-01-29T17:42:24+00:00","mainEntityOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/"},"wordCount":3004,"commentCount":0,"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1","keywords":["Arriero","Avi\u00f3n","canibalismo","Cordillera de los Andes","H\u00e9roe","Nando Parrado","olvido","pel\u00edcula","sociedad de la nieve","Supervivencia","tragedia","Tragedia de los Andes","uruguayos","viven"],"articleSection":["Historias","tercera","Videos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/","url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/","name":"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes - El Regional","isPartOf":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#primaryimage"},"image":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1","datePublished":"2024-01-22T23:40:46+00:00","dateModified":"2024-01-29T17:42:24+00:00","author":{"@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354"},"breadcrumb":{"@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#primaryimage","url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1","contentUrl":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1","width":1130,"height":636},{"@type":"BreadcrumbList","@id":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/la-sociedad-de-la-nieve-el-heroe-olvidado-que-salvo-a-los-sobrevivientes-de-la-tragedia-de-los-andes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/"},{"@type":"ListItem","position":2,"name":"\u201cLa Sociedad de la Nieve\u201d: El h\u00e9roe olvidado que salv\u00f3 a los sobrevivientes de la tragedia de los Andes"}]},{"@type":"WebSite","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#website","url":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/","name":"El Regional","description":"Mucho m\u00e1s que informaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/elregionalvm.com.ar\/noticias-villa-maria\/#\/schema\/person\/a0fb9c422317faca23d50163151bc354","name":"Contenidos El Regional","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265b27cb2209af7bb3a1318f03305787d7981a5cc6e6cd08fe5a4ecdf99d4b48?s=96&d=mm&r=g","caption":"Contenidos El Regional"},"url":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/author\/contenido\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elregionalvm.com.ar\/noticias-villa-maria\/wp-content\/uploads\/2024\/01\/sociedad-de-la-nieve-fotos-comparativas-avion-saludo-andes-2.jpg?fit=1130%2C636&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/88887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/comments?post=88887"}],"version-history":[{"count":2,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/88887\/revisions"}],"predecessor-version":[{"id":88896,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/posts\/88887\/revisions\/88896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media\/88892"}],"wp:attachment":[{"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/media?parent=88887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/categories?post=88887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionalvm.com.ar\/noticias-villa-maria\/wp-json\/wp\/v2\/tags?post=88887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}